{"id":1244,"date":"2020-11-14T08:56:09","date_gmt":"2020-11-14T07:56:09","guid":{"rendered":"https:\/\/ekiwi.de\/?p=1244"},"modified":"2020-11-14T08:56:09","modified_gmt":"2020-11-14T07:56:09","slug":"weihnachtsfeiern-dieses-jahr-nur-digital","status":"publish","type":"post","link":"https:\/\/ekiwi.de\/index.php\/1244\/weihnachtsfeiern-dieses-jahr-nur-digital\/","title":{"rendered":"Weihnachtsfeiern dieses Jahr nur digital"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_82_2 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Inhalt<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/ekiwi.de\/index.php\/1244\/weihnachtsfeiern-dieses-jahr-nur-digital\/#Ein_Hoch_auf_digitale_Kommunikationstechnologien\" >Ein Hoch auf digitale Kommunikationstechnologien<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/ekiwi.de\/index.php\/1244\/weihnachtsfeiern-dieses-jahr-nur-digital\/#Die_besten_Tools_fuer_eine_gelungene_Feier\" >Die besten Tools f\u00fcr eine gelungene Feier<\/a><\/li><\/ul><\/nav><\/div>\n<p>Dass dieses Jahr viele \u00dcberraschungen bereith\u00e4lt und sich wohl f\u00fcr immer in den K\u00f6pfen der Menschen festsetzt, ist nicht verwunderlich, schlie\u00dflich hat die Corona-Krise einiges ver\u00e4ndert. Besonders f\u00fcr Unternehmen bedeutet das Jahr 2020 weitreichende Umstrukturierungen in Bezug auf digitales Arbeiten, <a href=\"https:\/\/ekiwi.de\/index.php\/901\/4-wege-wie-die-technologie-die-geschaeftswelt-umgewandelt-hat\/\">neue Technologien und den Einsatz verschiedener Tools<\/a>, um auch in einer Krise wie dieser wettbewerbsf\u00e4hig zu bleiben und Ums\u00e4tze zu generieren.<\/p>\n<p>Digitale Tools erlebten 2020 einen echten Aufschwung, konnte beispielsweise die Video-Kommunikationssoftware Zoom die Ums\u00e4tze in einem Quartal vervierfachen. Die Aktie legte zu Spitzenzeiten um satte 40 Prozent zu. Das zeigt, wie Digitalisierung und Corona miteinander harmonieren und wie wichtig digitale Strukturen auch in Zukunft noch sein werden. Jetzt steht nat\u00fcrlich auch wieder die allj\u00e4hrliche Weihnachtsfeier an, die jedoch aufgrund der hohen Ansteckungsgefahr ausfallen muss. Daher findet auch dieses Event in vielen Firmen 2020 via Videokonferenz statt, damit die Weihnachtsfeier trotzdem abgehalten werden kann \u2013 nur eben unter Corona-Bedingungen.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Ein_Hoch_auf_digitale_Kommunikationstechnologien\"><\/span>Ein Hoch auf digitale Kommunikationstechnologien<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Planten viele Unternehmen und auch Eventfirmen bereits eine Weihnachtsfeier auf Abstand, wird aufgrund des neuen Lockdowns auch aus diesem Vorhaben nichts. F\u00fcr alle Feiern gelten nun wieder versch\u00e4rfte Regeln und konsequente Verbote, die ein solches Event schlichtweg unm\u00f6glich machen. Die Unsicherheit ist einfach zu gro\u00df und auch die Gefahr f\u00fcr die Gesundheit eines jeden einzelnen nicht tragbar. Besonders f\u00fcr Risikogruppen oder <a href=\"https:\/\/www.sundt.de\/blog\/immunschwaeche\/\">Menschen, bei denen eine Immunschw\u00e4che besteht<\/a>, kann eine virtuelle Weihnachtsfeier also eine gro\u00dfe Erleichterung sein, um in der Corona-Zeit trotzdem mit dem gesamten Team auf die besinnliche Zeit und das Jahr ansto\u00dfen zu k\u00f6nnen.<\/p>\n<p>Die Weihnachtsfeier ist eine der wichtigsten Veranstaltungen des Jahres, wird hier der Zusammenhalt gest\u00e4rkt, eine engere Bindung zwischen F\u00fchrungskr\u00e4ften und Arbeitnehmern geschaffen und Lob, Dank und Anerkennung sowie Aussichten auf das kommende Jahr ausgesprochen. Ein Lob kann schlie\u00dflich jetzt schon auf digitale Kommunikationstechnologien ausgesprochen werden, kann damit eine Weihnachtsfeier der etwas anderen Art trotzdem alle Mitarbeiter n\u00e4her zusammenbringen.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Die_besten_Tools_fuer_eine_gelungene_Feier\"><\/span>Die besten Tools f\u00fcr eine gelungene Feier<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Zoom erm\u00f6glicht Videotelefonate mit bis zu 100 Teilnehmern, die gute Verbindungsqualit\u00e4t ist ein Pluspunkt, der f\u00fcr die Anwendung immer wieder angepriesen wird. Neben der kostenlosen Version gibt es auch noch ein kostenpflichtiges Abo, welches besonders dann interessant wird, sollte die Konferenz l\u00e4nger als 40 Minuten dauern. Da dies bei der Weihnachtsfeier sicher der Fall sein wird, sollte dieser Faktor beachtet werden, denn in der kostenlosen Version bricht die Verbindung nach dieser Zeit schlie\u00dflich automatisch ab.<\/p>\n<p>Neben Zoom kommen auch weitere Tools infrage wie beispielsweise Skype. Bereits seit vielen Jahren kann sich die Anwendung f\u00fcr Videotelefonate etablieren und ist auch noch immer kostenlos f\u00fcr alle Anwender nutzbar. Die Teilnehmerzahl ist dabei allerdings auf 50 limitiert \u2013 f\u00fcr kleinere Teams ist die App daher wunderbar geeignet, gibt es anders als bei Zoom kein Zeitlimit.<\/p>\n<p>F\u00fcr besonders gro\u00dfe Teams eignet sich Microsoft Teams, welches eine Teilnehmerzahl von 250 erlaubt. Microsoft plant sogar, diese Beschr\u00e4nkung auf 300 zu erh\u00f6hen. Ob das jedoch immer ausgereizt wird, ist die andere Frage, wird das pers\u00f6nliche Miteinander bei so vielen Personen deutlich in Mitleidenschaft gezogen. Besser ist es dann, mehrere kleine Konferenzen zu er\u00f6ffnen und die Weihnachtsfeier lediglich innerhalb einer Abteilung oder eines Teams zu gestalten.<\/p>","protected":false},"excerpt":{"rendered":"<p>Dass dieses Jahr viele \u00dcberraschungen bereith\u00e4lt und sich wohl f\u00fcr immer in den K\u00f6pfen der Menschen festsetzt, ist nicht verwunderlich,<\/p>\n","protected":false},"author":2,"featured_media":1245,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[10],"tags":[221,220,219],"class_list":["post-1244","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-online-meeting","tag-skype","tag-weihnachten"],"_links":{"self":[{"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/posts\/1244","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/comments?post=1244"}],"version-history":[{"count":0,"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/posts\/1244\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/media\/1245"}],"wp:attachment":[{"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/media?parent=1244"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/categories?post=1244"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/tags?post=1244"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}