{"id":1751,"date":"2021-06-17T17:20:03","date_gmt":"2021-06-17T15:20:03","guid":{"rendered":"https:\/\/ekiwi.de\/?p=1751"},"modified":"2021-06-17T17:20:03","modified_gmt":"2021-06-17T15:20:03","slug":"der-wordpress-page-builder-fuer-landingpages","status":"publish","type":"post","link":"https:\/\/ekiwi.de\/index.php\/1751\/der-wordpress-page-builder-fuer-landingpages\/","title":{"rendered":"Der WordPress Page Builder f\u00fcr Landingpages"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Inhalt<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/ekiwi.de\/index.php\/1751\/der-wordpress-page-builder-fuer-landingpages\/#Was_ist_eine_Landingpage\" >Was ist eine Landingpage?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/ekiwi.de\/index.php\/1751\/der-wordpress-page-builder-fuer-landingpages\/#Die_wichtigsten_Elemente_fuer_eine_Landingpage\" >Die wichtigsten Elemente f\u00fcr eine Landingpage<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/ekiwi.de\/index.php\/1751\/der-wordpress-page-builder-fuer-landingpages\/#Was_macht_den_WordPress_Page_Builder_fuer_Dich_so_interessant\" >Was macht den WordPress Page Builder f\u00fcr Dich so interessant?<\/a><\/li><\/ul><\/nav><\/div>\n<p>Wenn Du eine Webseite erstellen m\u00f6chtest, dann solltest Du einen<a href=\"https:\/\/onlinemarketing-mastermind.de\/software-tools\/beste-wordpress-page-builder-plugins\/\" target=\"_blank\" rel=\"noopener\"> WordPress Page Builder<\/a> nutzen. Dieser hilft Dir, selbst wenn Du nicht programmieren kannst und Dich nie wirklich mit dem Thema CSS auseinandergesetzt hast. Du kannst so relativ einfach eine Webseite erstellen, wenn Du zwar ein gutes Auge f\u00fcr das Design hast, Dir aber weitere Kenntnisse fehlen.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Was_ist_eine_Landingpage\"><\/span><b>Was ist eine Landingpage?<\/b><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Die Landingpage befindet sich innerhalb Deiner Webseite und hat das Ziel m\u00f6glichst viele Nutzer auf Deine Seite zu holen. Somit dient die Landingpage in erster Linie dazu, die Besucher Deiner Webseite zu bestimmten Handlungen zu f\u00fchren. Das Besondere an der Landingpage ist, dass sie sowohl optisch wie auch vom Aufbau von den anderen Seiten abweicht. Der Grund hierf\u00fcr ist, dass sie den Besucher nicht ablenken darf. Besucher haben nur die M\u00f6glichkeit eine gew\u00fcnschte Handlung auszuf\u00fchren oder die Seite komplett zu verlassen. Alles andere ist unn\u00fctz und auch nicht gew\u00fcnscht. Daher sollte es kein Men\u00fc auf der Landingpage geben, welches die Besucher ablenkt.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Die_wichtigsten_Elemente_fuer_eine_Landingpage\"><\/span><b>Die wichtigsten Elemente f\u00fcr eine Landingpage<\/b><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Damit die Landingpage ihren Zweck erf\u00fcllt, muss sie ein paar wesentliche Elemente enthalten. Mit dem WordPress Page Builder kannst Du daf\u00fcr sorgen, dass die richtigen Elemente an der richtigen Stelle sind, um Deine Besucher zu einer Aktion zu animieren.<\/p>\n<p>Die 5 wichtigen Elemente sind:<\/p>\n<ul>\n<li>\u00a0<b>Headline und Subline<\/b> &#8211; Das erste was Besucher sehen ist die \u00dcberschrift. Daher muss sie den Besucher sofort \u00fcberzeugen. Die \u00dcberschrift sollte Dein Alleinstellungsmerkmal (USP) hervorheben.<\/li>\n<li>\u00a0<b>Hero Shot<\/b> &#8211; Ein Foto Deines Produkts, damit Besucher es sich vorstellen k\u00f6nnen. Vergiss dabei nicht den Nutzungskontext.<\/li>\n<li>\u00a0<b>Vorteile<\/b> &#8211; Gib dem Besucher mehr Informationen zu dem entsprechenden Produkt. F\u00fchre dazu die Vorteile stichpunktartig auf und fasse sie dann in einem Absatz zusammen.<\/li>\n<li>\u00a0<b>Call-to-Action<\/b> &#8211; Mit der Landingpage musst Du den Besucher von einer Handlung \u00fcberzeugen. Daf\u00fcr ben\u00f6tigst Du die Handlungsaufforderung (Call-to-Action).<\/li>\n<li>\u00a0<b>Vertrauen und Social Proof<\/b> &#8211; Baue Vertrauen f\u00fcr Deine Besucher auf, indem Du auf Trust Elements zur\u00fcckgreifst.<\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"Was_macht_den_WordPress_Page_Builder_fuer_Dich_so_interessant\"><\/span>Was macht den WordPress Page Builder f\u00fcr Dich so interessant?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Beim Recherchieren im Netz hast Du sicherlich festgestellt, dass es eine Reihe von verschiedenen WordPress Page Buildern gibt. Wenn Du Dir nicht sicher bist, welches der Tools Du nutzen m\u00f6chtest, dann nutze die kostenlose Testphase oder die M\u00f6glichkeit f\u00fcr nur 1 \u20ac das Tool ein paar Tage auszuprobieren. Du wirst schnell erkennen mit welchen WordPress Page Builder Du am besten umgehen kannst und welcher Deiner Anforderungen gerecht wird.<\/p>","protected":false},"excerpt":{"rendered":"<p>Wenn Du eine Webseite erstellen m\u00f6chtest, dann solltest Du einen WordPress Page Builder nutzen. Dieser hilft Dir, selbst wenn Du<\/p>\n","protected":false},"author":2,"featured_media":278,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[51],"tags":[356,346,357,355,344,345],"class_list":["post-1751","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-wordpress","tag-bog","tag-homepage","tag-landingpage","tag-webpage","tag-webseite","tag-website"],"_links":{"self":[{"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/posts\/1751","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/comments?post=1751"}],"version-history":[{"count":0,"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/posts\/1751\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/media\/278"}],"wp:attachment":[{"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/media?parent=1751"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/categories?post=1751"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/tags?post=1751"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}