{"id":2572,"date":"2022-04-14T14:33:38","date_gmt":"2022-04-14T12:33:38","guid":{"rendered":"https:\/\/ekiwi.de\/?p=2572"},"modified":"2022-04-14T14:33:38","modified_gmt":"2022-04-14T12:33:38","slug":"nordrhein-westfalen-oeffnet-sich-mit-dem-neuen-gesetz-dem-gluecksspiel","status":"publish","type":"post","link":"https:\/\/ekiwi.de\/index.php\/2572\/nordrhein-westfalen-oeffnet-sich-mit-dem-neuen-gesetz-dem-gluecksspiel\/","title":{"rendered":"Nordrhein-Westfalen \u00f6ffnet sich mit dem neuen Gesetz dem Gl\u00fccksspiel"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_82_2 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Inhalt<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/ekiwi.de\/index.php\/2572\/nordrhein-westfalen-oeffnet-sich-mit-dem-neuen-gesetz-dem-gluecksspiel\/#Offizielle_Onlinegluecksspielerlaubnis_in_Nordrhein-Westfalen\" >Offizielle Onlinegl\u00fccksspielerlaubnis in Nordrhein-Westfalen<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/ekiwi.de\/index.php\/2572\/nordrhein-westfalen-oeffnet-sich-mit-dem-neuen-gesetz-dem-gluecksspiel\/#Die_Rahmenbedingungen_des_neuen_Gesetzes\" >Die Rahmenbedingungen des neuen Gesetzes<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/ekiwi.de\/index.php\/2572\/nordrhein-westfalen-oeffnet-sich-mit-dem-neuen-gesetz-dem-gluecksspiel\/#Kritik_am_neuen_Gesetz\" >Kritik am neuen Gesetz<\/a><\/li><\/ul><\/nav><\/div>\n<p>Nordrhein-Westfalen hat eine lange Tradition darin das Gl\u00fccksspiel abzulehnen und zu verbieten. Letzten Sommer wurden mit dem neuen Gl\u00fccksspielgesetz bundesweit die Rahmenbedingungen f\u00fcr eine Legalisierung des Gl\u00fccksspiels geschaffen.<\/p>\n<p>Bereits damals war es vielen Branchenexperten schon klar, dass Nordrhein-Westfalen, als Bundesland mit den meisten Einwohnern in Deutschland, sich nicht ewig dem Gl\u00fccksspiel und den hieraus resultierenden M\u00f6glichkeiten verwehren kann.<\/p>\n<p>Schleswig-Holstein hatte es bereits seit Jahren mit Gl\u00fccksspielanbietern, wie <a href=\"https:\/\/www.hyperino.de\/\" target=\"_blank\" rel=\"noopener\">Hyperino DE<\/a>, vorgemacht, dass das Gl\u00fccksspiel und dessen Legalisierung in Deutschland funktionieren kann.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Offizielle_Onlinegluecksspielerlaubnis_in_Nordrhein-Westfalen\"><\/span>Offizielle Onlinegl\u00fccksspielerlaubnis in Nordrhein-Westfalen<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Der Landtag von Nordhrein-Westfalen hat in einem offiziellen Statement dann tats\u00e4chlich bekannt gegeben, dass f\u00fcnf Lizenzen f\u00fcr das Onlinegl\u00fccksspiel vergeben werden. Damit ist es nach Schleswig-Holstein, trotz der bundesweiten, gesetzlichen Vorlage, erst das zweite Bundesland in Deutschland, welches das Onlinegl\u00fccksspiel zul\u00e4sst.<\/p>\n<p>Das Ziel hierbei ist laut den Beh\u00f6rden, dass der Markt besser reguliert und damit vor allem dem Schwarzmarkt in Sachen Onlinegl\u00fccksspiel, welcher insbesondere in den letzten Jahren in Deutschland sehr gro\u00df war, Einhalt geboten wird. Hierf\u00fcr sorgen, sollen auch die strengen Regeln des neuen Gl\u00fccksspielgesetz, in denen beispielsweise festgehalten ist, dass gewisse Richtlinien zum Schutz der Spieler eingehalten werden m\u00fcssen.<\/p>\n<p>Nordrhein-Westfalen hat ebenfalls im Rahmen dieses Gesetzes zun\u00e4chst einmal die ersten Spiele, wie Roulette, Black Jack und Baccarat, akzeptiert und wartet noch mit den Lizenzen f\u00fcr Poker und Slotmaschinen, die dann vermutlich zu einem sp\u00e4teren Zeitpunkt folgen werden.<\/p>\n<p><a href=\"\/wp-content\/uploads\/2022\/04\/spiel-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2574\" src=\"\/wp-content\/uploads\/2022\/04\/spiel-2.jpg\" alt=\"\" width=\"602\" height=\"459\" srcset=\"\/wp-content\/uploads\/2022\/04\/spiel-2.jpg 602w, \/wp-content\/uploads\/2022\/04\/spiel-2-300x229.jpg 300w\" sizes=\"auto, (max-width: 602px) 100vw, 602px\" \/><\/a><\/p>\n<h2><span class=\"ez-toc-section\" id=\"Die_Rahmenbedingungen_des_neuen_Gesetzes\"><\/span>Die Rahmenbedingungen des neuen Gesetzes<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Das neue Gesetz wurde letztes Jahr vor allem von der Politik als Konsens gefeiert, weil diese sich insbesondere in Form der SPD und CDU lange nicht hatte einigen k\u00f6nnen, ob es bundesweit zu einer Erlaubnis f\u00fcr das Onlinegl\u00fccksspiel kommen sollte.<\/p>\n<p>Es wurde jedoch tats\u00e4chlich ein Konsens gefunden, welcher eine strenge Regulierung verschiedener Bereiche sowie hohe steuerliche Abgaben in H\u00f6he von 5,3% vorsieht.<\/p>\n<p>Die Regulierung au\u00dferdem im Allgemeinen soll daf\u00fcr sorgen, dass die notwendigen Rahmenbedingungen daf\u00fcr geschaffen werden, dass das Spielverhalten der einzelnen Teilnehmer in einem kontrollierbaren Rahmen gehalten werden kann.<\/p>\n<p>Hierf\u00fcr m\u00fcssen die Anbieter von Onlinegl\u00fccksspielen daf\u00fcr sorgen, dass diese gewissen Anforderungen in Sachen Design, Layout und Funktion entsprechen.<\/p>\n<p>Au\u00dferdem soll durch die <a href=\"https:\/\/www.gluecksspiel-behoerde.de\/index.php\" target=\"_blank\" rel=\"noopener\">Gemeinsame Gl\u00fccksspielbeh\u00f6rde der L\u00e4nder<\/a>, die durch Annie Poggemenan geleitet wird, sichergestellt werden, dass eine zentrale Stelle geschaffen wird. In dieser zentralen Beh\u00f6rde sollen dann beispielsweise die Daten der Spieler gespeichert werden, um nachvollziehen zu k\u00f6nnen, bei welchen Onlinecasinos eine einzelne Person angemeldet ist und ob diese m\u00f6glicherweise mit mehr Geld spielt als ihr eigentlich zur Verf\u00fcgung steht.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Kritik_am_neuen_Gesetz\"><\/span>Kritik am neuen Gesetz<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Insbesondere von Seiten des Gl\u00fccksspiels sowie naheliegender Beh\u00f6rden, wie beispielsweise dem Deutschen Sportwettenverband und der European Gaming and Betting Association kam bereits heftige Kritik in Bezug auf die hohen Steuern und die generellen Auflagen, welche laut diesen zwei Beh\u00f6rden den Wettbewerb verzerren.<\/p>\n<p>Diese Wettbewerbsverzerrung w\u00fcrde dann anschlie\u00dfend in zahlreichen Nachteilen f\u00fcr deutsche Teams und Sportler m\u00fcnden, wie beispielsweise die schlechteren Chancen auf Sponsorings und Co., was sogar zu einem Antrag auf EU-Ebene gef\u00fchrt hat, welcher in den n\u00e4chsten Monaten durch die zust\u00e4ndigen Beh\u00f6rden gekl\u00e4rt werden soll.<\/p>\n<p>Aus all diesen Gr\u00fcnden bleibt es wohl mit Spannung zu verfolgen, ob nach Nordrhein-Westfalen noch andere L\u00e4nder folgen und inwiefern sich legales Gl\u00fccksspiel im Rahmen der gesetzlichen Bedingungen durchsetzen kann.<\/p>","protected":false},"excerpt":{"rendered":"<p>Nordrhein-Westfalen hat eine lange Tradition darin das Gl\u00fccksspiel abzulehnen und zu verbieten. Letzten Sommer wurden mit dem neuen Gl\u00fccksspielgesetz bundesweit<\/p>\n","protected":false},"author":2,"featured_media":2573,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[10],"tags":[],"class_list":["post-2572","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/posts\/2572","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/comments?post=2572"}],"version-history":[{"count":0,"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/posts\/2572\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/media\/2573"}],"wp:attachment":[{"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/media?parent=2572"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/categories?post=2572"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/tags?post=2572"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}