{"id":5377,"date":"2023-09-09T07:33:02","date_gmt":"2023-09-09T05:33:02","guid":{"rendered":"https:\/\/ekiwi.de\/?p=5377"},"modified":"2023-09-09T08:34:36","modified_gmt":"2023-09-09T06:34:36","slug":"mit-dem-neuen-cleanchanger-siebwechsler-der-jetzt-patentiert-wurde-ist-ein-100iges-recycling-von-kunststoff-moeglich","status":"publish","type":"post","link":"https:\/\/ekiwi.de\/index.php\/5377\/mit-dem-neuen-cleanchanger-siebwechsler-der-jetzt-patentiert-wurde-ist-ein-100iges-recycling-von-kunststoff-moeglich\/","title":{"rendered":"Mit dem neuen CleanChanger\u00ae Siebwechsler, der jetzt patentiert wurde, ist ein 100%iges Recycling von Kunststoff m\u00f6glich"},"content":{"rendered":"<p>Kunststoffrecycling ist heute eine \u00f6kologische und wirtschaftliche Notwendigkeit, die Unternehmen nicht ignorieren k\u00f6nnen.<\/p>\n<p>Damit dies m\u00f6glich ist, ist das Verfahren der Filtration von Polymeren <strong>unverzichtbar<\/strong>, und eine der gr\u00f6\u00dften Herausforderungen in diesem Bereich ist es, dieses Verfahren so effizient wie m\u00f6glich zu gestalten. Eine wirksame Filtration reduziert den Abfall und garantiert ein hohes Ma\u00df an Reinheit und Sauberkeit f\u00fcr die zur\u00fcckgewonnenen Kunststoffe.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-5378\" src=\"\/wp-content\/uploads\/2023\/09\/clean-changer-siebwechsler.jpg\" alt=\"\" width=\"650\" height=\"434\" srcset=\"\/wp-content\/uploads\/2023\/09\/clean-changer-siebwechsler.jpg 650w, \/wp-content\/uploads\/2023\/09\/clean-changer-siebwechsler-300x200.jpg 300w, \/wp-content\/uploads\/2023\/09\/clean-changer-siebwechsler-120x80.jpg 120w, \/wp-content\/uploads\/2023\/09\/clean-changer-siebwechsler-480x320.jpg 480w\" sizes=\"auto, (max-width: 650px) 100vw, 650px\" \/><\/p>\n<p>Mit diesem Schwerpunkt hat <a href=\"https:\/\/www.bdplast.com\/de\/\" target=\"_blank\" rel=\"noopener\"><strong>BD Plast<\/strong><\/a>, ein italienisches Unternehmen, das sich auf Filtersysteme spezialisiert hat, CleanChanger\u00ae entwickelt, den selbstreinigenden hydraulischen Siebwechsler mit kontinuierlichem Durchfluss &#8211; eine besonders <strong>innovative L\u00f6sung<\/strong>, in die jahrelange Forschung und Entwicklung eingeflossen sind und die k\u00fcrzlich <strong>patentiert<\/strong> wurde.<\/p>\n<p><em>\u201eRecyceltes Plastik zu verarbeiten, ohne Material zu verschwenden, ohne es in der Umwelt zu verstreuen, und einen Sauberkeitsgrad zu garantieren, der dem von neuem Plastik entspricht, ist eine immer dringendere Forderung unserer Kunden und des gesamten Marktes\u201c, <\/em>erkl\u00e4rt Dante Boicelli, Gr\u00fcnder von BD Plast. <em>\u201eUnd unser Unternehmen nimmt genau diese Bed\u00fcrfnisse unserer Stakeholder in unsere Arbeit auf: So entwickeln wir unsere Projekte und erzielen hervorragende Ergebnisse.\u201c <\/em><\/p>\n<p>So wie der <strong>patentierte CleanChanger\u00ae-Siebwechsler<\/strong>, der die 100%ige R\u00fcckgewinnung des Materials erlaubt und die gesamte Branche revolutionieren k\u00f6nnte.<\/p>\n<p>Es handelt sich in der Tat um einen echten Durchbruch, denn das <strong>automatische Aussto\u00dfsystem f\u00fcr Lochplatten<\/strong> erlaubt eine extrem hohe Autonomie und optimiert das gesamte Extrusionsverfahren.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-5380\" src=\"\/wp-content\/uploads\/2023\/09\/clean-changer-team.jpg\" alt=\"\" width=\"650\" height=\"434\" srcset=\"\/wp-content\/uploads\/2023\/09\/clean-changer-team.jpg 650w, \/wp-content\/uploads\/2023\/09\/clean-changer-team-300x200.jpg 300w, \/wp-content\/uploads\/2023\/09\/clean-changer-team-120x80.jpg 120w, \/wp-content\/uploads\/2023\/09\/clean-changer-team-480x320.jpg 480w\" sizes=\"auto, (max-width: 650px) 100vw, 650px\" \/><\/p>\n<p>Die L\u00f6sung wurde f\u00fcr Verfahren zur Granulierung, zum Compounding, Recycling, f\u00fcr Blas- und Gie\u00dffolien, Flachfolien, Rohre, Profile, Stranggranulierung, Unterwassergranulierung, Hotmeltbeschichtung und Masterbatching entwickelt und getestet. Der CleanChanger<sup>\u00ae<\/sup> ist mit einer v\u00f6llig autonomen Selbstreinigungssequenz ausgestattet, die von einer SPS mit Touchscreen gesteuert wird, und kann dank eines hocheffizienten Reinigungszyklus der Siebe eine weitere Reduzierung der Produktionskosten garantieren; ein Hochleistungsprodukt, das die gesamte Produktionskette effizienter und nachhaltiger macht.<\/p>\n<p><em>\u201eUnser Unternehmen stellt j\u00e4hrlich etwa 1400 Systeme her, bietet eine breites Sortiment an Filtern, Siebwechslern und anderen Komponenten, und entwirft Ad-hoc-L\u00f6sungen f\u00fcr jeden Bedarf: Wir begleiten unsere Kunden vom Entwurf der Maschine bis zu ihrer Montage direkt vor Ort&#8220;, <\/em>f\u00e4hrt Boicelli fort.<em> \u201eWir beliefern mehr als 50 L\u00e4nder auf der ganzen Welt und tun dies stets mit Leidenschaft, Hingabe und Enthusiasmus: So erreichen wir Ziele wie die Schaffung eines Produkts wie CleanChanger\u00ae, und wir sind sehr stolz darauf, dass diese innovative L\u00f6sung jetzt patentiert ist.\u201c<\/em><\/p>\n<p><strong><em>BD Plast Filtering Systems<\/em><\/strong><\/p>\n<p><em>BD Plast ist das 1986 in Bondeno, in der Provinz Ferrara, gegr\u00fcndete Familienunternehmen, das sich der Herstellung und dem Vertrieb von Siebwechslern f\u00fcr Kunststoffextrusionsanlagen widmet, und mittlerweile seine Position in Italien durch nachgeschaltete Technologien gefestigt hat.<\/em><\/p>\n<p><em>Das Unternehmen aus der Region Emilia verf\u00fcgt \u00fcber rund f\u00fcnfzig hochqualifizierte Mitarbeiter, die durch die Entwicklung und Realisierung neuer Maschinen- und Produktlinien wie Extrusionsadapter, Schmelzrohre und Kr\u00fcmmer engagiert das Wachstum des Unternehmens tragen, im Laufe der Zeit wichtige internationale Partnerschaften konsolidieren und den Kundendienst im Sinne eines echten Mehrwerts f\u00fcr maximale Kundenzufriedenheit maximieren. <\/em><\/p>\n<p><em>37 Jahre Innovation und die Entwicklung von Ideen und Vorschl\u00e4gen f\u00fcr innovative L\u00f6sungen kennzeichnen den Ansatz von BD Plast auf dem Markt, mit einer Leidenschaft f\u00fcr Erneuerung nicht nur im Hinblick auf das Angebot von Systemen, sondern auch f\u00fcr strategische Entscheidungen, die darauf abzielen, auf die verschiedenen Ver\u00e4nderungen im Herstellungskontext zu reagieren.<\/em><\/p>\n<p><strong>Weitere Informationen:<\/strong><\/p>\n<p>CleanChanger\u00ae: <a href=\"https:\/\/cleanchanger.de\/\">https:\/\/cleanchanger.de\/<\/a><br \/>\nBD Plast:\u00a0<a href=\"http:\/\/www.bdplast.com\/de\">www.bdplast.com\/de<\/a><\/p>\n<p>BD PLAST FILTERING SYSTEMS SRL<br \/>\nvia Copernico 32, 44012 Bondeno \u2013 Ferrara, Italien<br \/>\nTel.:\u00a0<a href=\"callto:+39%200532%20888811\"><u>+39 0532 888811<\/u><\/a> &#8211; <a href=\"mailto:info@bdplast.com\">info@bdplast.com<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Kunststoffrecycling ist heute eine \u00f6kologische und wirtschaftliche Notwendigkeit, die Unternehmen nicht ignorieren k\u00f6nnen. Damit dies m\u00f6glich ist, ist das Verfahren<\/p>\n","protected":false},"author":2,"featured_media":5382,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[10],"tags":[1042,1043],"class_list":["post-5377","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-kunststoff","tag-recycling"],"_links":{"self":[{"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/posts\/5377","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/comments?post=5377"}],"version-history":[{"count":0,"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/posts\/5377\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/media\/5382"}],"wp:attachment":[{"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/media?parent=5377"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/categories?post=5377"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/tags?post=5377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}