{"id":5384,"date":"2023-09-10T14:37:54","date_gmt":"2023-09-10T12:37:54","guid":{"rendered":"https:\/\/ekiwi.de\/?p=5384"},"modified":"2023-09-10T14:45:47","modified_gmt":"2023-09-10T12:45:47","slug":"die-dguv-vorschrift-3-was-steckt-hinter-der-regelmaessigen-elektropruefung","status":"publish","type":"post","link":"https:\/\/ekiwi.de\/index.php\/5384\/die-dguv-vorschrift-3-was-steckt-hinter-der-regelmaessigen-elektropruefung\/","title":{"rendered":"Die DGUV Vorschrift 3: Was steckt hinter der regelm\u00e4\u00dfigen Elektropr\u00fcfung?"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Inhalt<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/ekiwi.de\/index.php\/5384\/die-dguv-vorschrift-3-was-steckt-hinter-der-regelmaessigen-elektropruefung\/#Was_ist_die_DGUV_Vorschrift_3\" >Was ist die DGUV Vorschrift 3?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/ekiwi.de\/index.php\/5384\/die-dguv-vorschrift-3-was-steckt-hinter-der-regelmaessigen-elektropruefung\/#Warum_ist_das_ueberhaupt_notwendig\" >Warum ist das \u00fcberhaupt notwendig?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/ekiwi.de\/index.php\/5384\/die-dguv-vorschrift-3-was-steckt-hinter-der-regelmaessigen-elektropruefung\/#Wie_oft_muss_eine_Pruefung_erfolgen\" >Wie oft muss eine Pr\u00fcfung erfolgen?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/ekiwi.de\/index.php\/5384\/die-dguv-vorschrift-3-was-steckt-hinter-der-regelmaessigen-elektropruefung\/#Wer_darf_pruefen\" >Wer darf pr\u00fcfen?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/ekiwi.de\/index.php\/5384\/die-dguv-vorschrift-3-was-steckt-hinter-der-regelmaessigen-elektropruefung\/#Fazit\" >Fazit<\/a><\/li><\/ul><\/nav><\/div>\n<p>Wer in einem Unternehmen oder dem \u00f6ffentlichen Dienst arbeitet, wird es kennen, elektrische Ger\u00e4te m\u00fcssen regelm\u00e4\u00dfig \u00fcberpr\u00fcft werden.<\/p>\n<p><!--more--><\/p>\n<p>Bei uns in der Firma gilt: kein Betrieb von elektrischen Ger\u00e4ten ohne E-Check. Egal ob Kaffeemaschine, Computer oder Netzteil zum Laden des Smartphones.<\/p>\n<p>Regelm\u00e4\u00dfig kommt daher eine Firma, welche die alten und neuen Ger\u00e4te pr\u00fcft, aufnimmt. Gepr\u00fcft wird alles, ob gro\u00df, ob klein und nat\u00fcrlich sind wir auch angehalten, neue Ger\u00e4te direkt zu melden.<\/p>\n<p>Dahinter steckt eine Vorschrift, die DGUV 3. Wie so oft steckt hinter dem Namen eine Abk\u00fcrzung, in diesem Fall \u201cDeutsche gesetzliche Unfallversicherung\u201d.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Was_ist_die_DGUV_Vorschrift_3\"><\/span>Was ist die DGUV Vorschrift 3?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Die <a href=\"https:\/\/www.e-service-check.de\/heisst-dguv-3\/\">DGUV Vorschrift 3<\/a> ist eine der zentralen Unfallverh\u00fctungsvorschriften in Deutschland, die sich auf elektrische Anlagen und Betriebsmittel konzentriert. Sie stellt sicher, dass diese Anlagen und Mittel sicher betrieben werden k\u00f6nnen, ohne dass Mitarbeiter oder andere Personen gef\u00e4hrdet werden.<\/p>\n<p>Gem\u00e4\u00df dieser Vorschrift sind Arbeitgeber verpflichtet, sicherzustellen, dass alle elektrischen Anlagen und Betriebsmittel regelm\u00e4\u00dfig gepr\u00fcft werden.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5385\" src=\"\/wp-content\/uploads\/2023\/09\/dguv_1.jpg\" alt=\"\" width=\"800\" height=\"600\" srcset=\"\/wp-content\/uploads\/2023\/09\/dguv_1.jpg 800w, \/wp-content\/uploads\/2023\/09\/dguv_1-300x225.jpg 300w, \/wp-content\/uploads\/2023\/09\/dguv_1-768x576.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<h2><span class=\"ez-toc-section\" id=\"Warum_ist_das_ueberhaupt_notwendig\"><\/span>Warum ist das \u00fcberhaupt notwendig?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Strom ist unsichtbar und damit gef\u00e4hrlich. Ein kaputtes Kabel, ein China-Netzteil aus fragw\u00fcrdiger Produktion kann nicht nur zu Stromschl\u00e4gen f\u00fchren, sondern auch anderes Unheil nach sich ziehen, wie z.B. einen Brand.<\/p>\n<p>Alles ist vermeidbar, sofern die elektrischen Anlagen und Betriebsmittel regelm\u00e4\u00dfig \u00fcberpr\u00fcft werden. Dazu kommt die Haftungsfrage, am Ende haftet ggf. der Arbeitnehmer, wenn ein Arbeitsunfall passiert.<\/p>\n<p>Um sicherzustellen, dass kein Pr\u00fcftermin verpasst wird, empfiehlt es sich, ein Pr\u00fcfprotokoll zu f\u00fchren und einen verantwortlichen Mitarbeiter zu benennen.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Wie_oft_muss_eine_Pruefung_erfolgen\"><\/span>Wie oft muss eine Pr\u00fcfung erfolgen?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Wie immer gilt, h\u00e4ngt davon ab. Was ist es f\u00fcr ein Ger\u00e4t, was sind die Einsatzbedingungen.<\/p>\n<p>W\u00e4hrend beispielsweise eine fest installierte elektrische Anlage in einem B\u00fcrogeb\u00e4ude m\u00f6glicherweise nur alle paar Jahre gepr\u00fcft werden muss, kann es sein, dass ein Werkzeug in einer feuchten und staubigen Werkstatt j\u00e4hrlich \u00fcberpr\u00fcft werden muss.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Wer_darf_pruefen\"><\/span>Wer darf pr\u00fcfen?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Die Pr\u00fcfung selbst darf nicht jeder vornehmen:<\/p>\n<p>Die \u00dcberpr\u00fcfung nach der DGUV Vorschrift 3 darf nur von speziell ausgebildeten Personen durchgef\u00fchrt werden, die \u00fcber die notwendige Fachkunde verf\u00fcgen. Diese Fachkunde wird in der Regel durch eine entsprechende berufliche Ausbildung und zus\u00e4tzliche Qualifizierungsschulungen erworben.<\/p>\n<p>Neben der entsprechenden Qualifikation m\u00fcssen die Personen die erforderlichen Pr\u00fcfwerkzeuge und -ger\u00e4te besitzen und verwenden.<\/p>\n<p>Das bedeutet, dass nicht jeder Elektriker automatisch zur Durchf\u00fchrung solcher Pr\u00fcfungen berechtigt ist; vielmehr muss die spezifische Fachkunde zur Pr\u00fcfung nach DGUV Vorschrift 3 nachgewiesen werden.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Fazit\"><\/span>Fazit<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Die DGUV Vorschrift 3 mag auf den ersten Blick wie eine weitere b\u00fcrokratische Regelung erscheinen, die Unternehmen belastet. Doch ihre Bedeutung kann nicht hoch genug eingesch\u00e4tzt werden. Sie sorgt daf\u00fcr, dass elektrische Anlagen und Betriebsmittel sicher betrieben werden k\u00f6nnen und reduziert das Risiko schwerer Unf\u00e4lle oder Br\u00e4nde.<\/p>\n<p>Jeder Arbeitgeber sollte daher sicherstellen, dass die Pr\u00fcfungen ordnungsgem\u00e4\u00df und regelm\u00e4\u00dfig durchgef\u00fchrt werden. Dazu geh\u00f6rt auch eine entsprechende Sensibilisierung der Mitarbeiter, dass diese neue Ger\u00e4te melden und pr\u00fcfen lassen. Die Regelung gilt am Ende auch f\u00fcr die mitgebrachte Senseo Kaffeemaschine.<\/p>","protected":false},"excerpt":{"rendered":"<p>Wer in einem Unternehmen oder dem \u00f6ffentlichen Dienst arbeitet, wird es kennen, elektrische Ger\u00e4te m\u00fcssen regelm\u00e4\u00dfig \u00fcberpr\u00fcft werden.<\/p>\n","protected":false},"author":1,"featured_media":5387,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[10],"tags":[],"class_list":["post-5384","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/posts\/5384","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/comments?post=5384"}],"version-history":[{"count":0,"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/posts\/5384\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/media\/5387"}],"wp:attachment":[{"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/media?parent=5384"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/categories?post=5384"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/tags?post=5384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}