{"id":626,"date":"2019-12-13T17:45:23","date_gmt":"2019-12-13T16:45:23","guid":{"rendered":"https:\/\/ekiwi.de\/?p=626"},"modified":"2019-12-16T18:11:16","modified_gmt":"2019-12-16T17:11:16","slug":"datenintegritaet-mit-rusvpn","status":"publish","type":"post","link":"https:\/\/ekiwi.de\/index.php\/626\/datenintegritaet-mit-rusvpn\/","title":{"rendered":"Datenintegrit\u00e4t mit RUSVPN"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_82_2 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Inhalt<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/ekiwi.de\/index.php\/626\/datenintegritaet-mit-rusvpn\/#Was_ist_Datenintegritaet\" >Was ist Datenintegrit\u00e4t<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/ekiwi.de\/index.php\/626\/datenintegritaet-mit-rusvpn\/#Sichere_Internetverbindung_mit_RUSVPN\" >Sichere Internetverbindung mit RUSVPN<\/a><\/li><\/ul><\/nav><\/div>\n<p>Heutzutage ist das Internet allgegenw\u00e4rtig. Es ist fast egal, wo auf der Welt man sich befindet, es gibt immer eine M\u00f6glichkeit sich mit dem Internet zu verbinden. Dies birgt aber die eine oder andere Gefahr, da das Internet <em>\u201eby design\u201c<\/em> nicht sicher ist. Ein offenes WLAN ist komfortabel und bietet meistens auch h\u00f6here Bandbreiten als der Mobiltarif oder schont so zu mindestens das allzu begrenzte Datenvolumen.<\/p>\n<p>Jedem Unternehmer sollten sich aber die Nackenhaare str\u00e4uben, wenn seine Mitarbeiter sensible Firmendaten \u00fcber ein offenes oder fremdes WLAN \u00fcbertragen. Und auch Privatpersonen sollten vorsichtig sein, was man unbefangen \u00fcber unsichere LANs und WLANs \u00fcbertr\u00e4gt. Denn theoretisch k\u00f6nnen diese Daten von Dritten mitgeschnitten und mitgelesen werden, die sich ebenfalls im selben Netz befinden.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Was_ist_Datenintegritaet\"><\/span>Was ist Datenintegrit\u00e4t<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Die betrifft also den Punkt der Datensicherheit. Im oben beschriebenen Fall sind die Daten vor den Augen Dritter nicht sicher und k\u00f6nnen missbraucht werden oder anderweitig ver\u00f6ffentlicht werden. Ganz schlimm wird es, wenn auf diese Art und Weise Credentials, also Zugangsdaten und Passw\u00f6rter, abgefangen werden, wobei hier inzwischen <strong>https<\/strong> auch sch\u00fctzt.<\/p>\n<p>Was ist aber wenn ein Dritter die Daten abf\u00e4ngt, modifiziert nach seinem Gutd\u00fcnken und dann weitersendet. In einem solchen Fall ist die Datenintegrit\u00e4t verletzt, denn Datenintegrit\u00e4t stellt sicher, dass Daten nicht ver\u00e4ndert werden (k\u00f6nnen).<\/p>\n<p>Datenintegrit\u00e4t gibt es auf vielen Ebenen der Elektronik, Computertechnik, Informatik bis hinein in den organisatorischen Bereich von Firmen. In der Elektronik und Digitaltechnik muss sichergestellt werden, dass sich nicht durch irgendwelche zuf\u00e4lligen Effekte oder Ausf\u00e4lle von Kondensatoren oder Transistoren es zu einem <em>\u201eBitkipper\u201c<\/em> kommt, welches falsche Daten verursacht. Eines der bekanntesten Verfahren ist das <a href=\"http:\/\/www.iti.fh-flensburg.de\/lang\/algorithmen\/code\/crc\/crc.htm\" target=\"_blank\" rel=\"noopener noreferrer\">CRC-Verfahren<\/a>, um solche Bitfehler zu erkennen.<\/p>\n<p>Im Rahmen der <a href=\"https:\/\/rusvpn.com\/de\/\" target=\"_blank\" rel=\"noopener noreferrer\">Datensicherheit soll die Datenintegrit\u00e4t<\/a> gew\u00e4hrt bleiben. Das hei\u00dft, es soll keine \u00c4nderung der Daten durch Dritte, z.B. <em>Man in the middle<\/em>, erfolgen und sofern es doch vorkommt m\u00f6chte man m\u00f6glichst Verfahren haben, um die Ver\u00e4nderung der Daten zu erkennen.<\/p>\n<p>Ein denkbares Szenario w\u00e4re, dass ein Mitarbeiter \u00fcbers Internet auf Firmendokumente aus der Buchhaltung zugreift. Hier w\u00fcrde es ausreichen, wenn ein Angreifer nur 1-2 gezielte Bytes im Datenstrom \u00e4ndert um das Zahlenwerk in der Buchhaltung zu verf\u00e4lschen und die Firma in ein schwer nachvollziehbares Chaos zu schicken. Ein anderer trivialer Fall kann sein, wenn bei einer <a href=\"https:\/\/da-software.de\/2019\/11\/reservierungsanfrage\/\" target=\"_blank\" rel=\"noopener noreferrer\">Reservierungsanfrage \u00fcber ein Reservierungsformular<\/a>, die \u00fcbertragenen Daten ge\u00e4ndert werden\u2026ein sch\u00f6nes Durcheinander!<\/p>\n<p><a href=\"https:\/\/rusvpn.com\/de\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-629\" src=\"\/wp-content\/uploads\/2019\/12\/laptop-vpn.jpg\" alt=\"VPN RUSVPN\" width=\"480\" height=\"270\" srcset=\"\/wp-content\/uploads\/2019\/12\/laptop-vpn.jpg 480w, \/wp-content\/uploads\/2019\/12\/laptop-vpn-300x169.jpg 300w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/a><\/p>\n<h3><span class=\"ez-toc-section\" id=\"Sichere_Internetverbindung_mit_RUSVPN\"><\/span>Sichere Internetverbindung mit RUSVPN<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Um den Mitarbeiter und Privatpersonen aber trotzdem die Freiheit und Flexibilit\u00e4t zu geben, die Dokumente von \u00fcberall sicher bearbeiten zu k\u00f6nnen, greift man auf ein <a href=\"https:\/\/rusvpn.com\/de\/download\/\" target=\"_blank\" rel=\"noopener noreferrer\">VPN von z.B. RUSVPN<\/a> zur\u00fcck. Bei RUSVPN handelt es sich um ein Virtual Privacy Network, bei welchem die Daten\u00fcbertragung verschl\u00fcsselt erfolgt. Ein solches VPN sollte man immer verwenden, wenn man sich im \u00f6ffentlichen Raum ins Internet einw\u00e4hlt. Die Daten werden \u00fcber die VPN-Verbindung verschl\u00fcsselt \u00fcbertragen. Ein Abfangen und eine Manipulation des Datenstroms ist zwar theoretisch immer noch m\u00f6glich, jedoch w\u00fcrde eine Manipulation zu bemerkbaren Fehlern f\u00fchren. Somit ist durch RUSVPN die Datenintegrit\u00e4t gesichert und auch das Mitlesen und Abfangen von Informationen ist aufgrund der Verschl\u00fcsselung nicht m\u00f6glich. Durch die Verschl\u00fcsselung bleibt man auch weitestgehend anonym. Ein weiterer Anwendungsfall ist, das Vorbeugen von <em>Deep Package Inspection (DPI)<\/em>. Hier wird unter anderem auch von staatlichen Beh\u00f6rden oder Telekommunikationsanbietern der Datenstrom automatisch auf seine Inhalte analysiert. So kann eine staatliche Zensur bez\u00fcglich bestimmter Inhalte stattfinden, indem diese Inhalte dann blockiert werden. Ein VPN bietet der <em>Deep Package Inspection<\/em> jedoch keine Angriffsfl\u00e4che.<\/p>\n<p>Bei der Nutzung von RUSVPN erh\u00e4lt man daf\u00fcr eine stabile und schnelle Verbindung. Und ganz wichtig bei der Nutzung eines solchen Dienstes ist, dass m\u00f6glichst viele Ger\u00e4tetypen unterst\u00fctzt werden. F\u00fcr RUSVPN gibt es f\u00fcr alle Ger\u00e4tetypen, wie Android, iOS, Desktop Windows, Desktop Apple, etc. passende VPN-Clients bzw. Browser-Plugins f\u00fcr zum Beispiel Chrome und Firefox.<\/p>\n<p>Dar\u00fcber hinaus bietet die Verwendung eines VPN-Dienst die M\u00f6glichkeit seine eigene IP-Adresse zu verschleiern und dadurch sich anonym in Internet zu bewegen. Jemand, der seine IP-Adresse verschleiert, wird oft b\u00f6se Absicht unterstellt. Aber meistens ist es umgekehrt. \u00dcber die IP-Adresse lassen sich jede Menge Informationen sammeln, der Standort ausfindig machen bis hin zur pers\u00f6nlichen Identit\u00e4tsfeststellung \u00fcber die <a href=\"https:\/\/www.datenschutz.org\/vorratsdatenspeicherung\/\" target=\"_blank\" rel=\"noopener noreferrer\">Vorratsdatenspeicherung<\/a>. So ist die IP-Verschleierung ein gutes Instrument f\u00fcr zum Beispiel politisch Verfolgte. Aber auch, wenn Internetdienste l\u00e4nderspezifisch blockiert werden, kann dies durch die Verwendung einer IP-Adresse aus einem anderen Land umgehen.<\/p>\n<p>Es gibt also vielf\u00e4ltige Anwendungsf\u00e4lle f\u00fcr ein VPN. Und wem seine Daten lieb sind, wird nicht umhin kommen, sich mit diesem Thema tiefergehend zu besch\u00e4ftigen.<\/p>","protected":false},"excerpt":{"rendered":"<p>Jedem Unternehmer sollten sich aber die Nackenhaare str\u00e4uben, wenn seine Mitarbeiter sensible Firmendaten \u00fcber ein offenes oder fremdes WLAN \u00fcbertragen. Und auch Privatpersonen sollten vorsichtig sein, was man unbefangen \u00fcber unsichere LANs und WLANs \u00fcbertr\u00e4gt.<\/p>\n","protected":false},"author":2,"featured_media":628,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[1],"tags":[111,110],"class_list":["post-626","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-unkategorisiert","tag-internet","tag-vpn"],"_links":{"self":[{"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/posts\/626","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/comments?post=626"}],"version-history":[{"count":0,"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/posts\/626\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/media\/628"}],"wp:attachment":[{"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/media?parent=626"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/categories?post=626"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/tags?post=626"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}