{"id":6762,"date":"2025-07-22T16:11:30","date_gmt":"2025-07-22T14:11:30","guid":{"rendered":"https:\/\/ekiwi.de\/?p=6762"},"modified":"2025-07-22T16:11:30","modified_gmt":"2025-07-22T14:11:30","slug":"bayreuth-ist-im-weltall-angekommen","status":"publish","type":"post","link":"https:\/\/ekiwi.de\/index.php\/6762\/bayreuth-ist-im-weltall-angekommen\/","title":{"rendered":"Bayreuth ist im Weltall angekommen"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_82_2 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Inhalt<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/ekiwi.de\/index.php\/6762\/bayreuth-ist-im-weltall-angekommen\/#Neue_Technologien_sorgen_fuer_nachhaltige_Veraenderungen\" >Neue Technologien sorgen f\u00fcr nachhaltige Ver\u00e4nderungen<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/ekiwi.de\/index.php\/6762\/bayreuth-ist-im-weltall-angekommen\/#Naehrstoffproduktion_in_der_Schwerelosigkeit\" >N\u00e4hrstoffproduktion in der Schwerelosigkeit<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/ekiwi.de\/index.php\/6762\/bayreuth-ist-im-weltall-angekommen\/#Erster_umbenannter_Flug_ist_wieder_sicher_gelandet\" >Erster umbenannter Flug ist wieder sicher gelandet<\/a><\/li><\/ul><\/nav><\/div>\n<p>Neue Technologien sorgen f\u00fcr nachhaltige Ver\u00e4nderungen. Wer jetzt an die USA oder China denkt, irrt. Auch Bayreuth ist in der Lage, die Welt zu ver\u00e4ndern &#8211; oder besser gesagt: die Entdeckung des Weltalls.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Neue_Technologien_sorgen_fuer_nachhaltige_Veraenderungen\"><\/span><b>Neue Technologien sorgen f\u00fcr nachhaltige Ver\u00e4nderungen<\/b><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Was vor ein paar Jahren noch undenkbar war, ist heute Realit\u00e4t geworden. Online Shops unterst\u00fctzen Konsumenten via Chat-Bots, liefern innerhalb von 24 Stunden und punkten mit individuellen Angeboten. Auch der Bereich des Gl\u00fccksspiels hat sich \u00fcber die Jahre gravierend ver\u00e4ndert: Musste man vor Jahren noch nach entsprechenden Adressen der Spielbanken suchen, auf \u00d6ffnungszeiten und Dresscode achten, so kann man heute problemlos <a href=\"https:\/\/www.pokerscout.com\/de\/casino\/mit-5-euro-einzahlung\/\" target=\"_blank\" rel=\"noopener noreferrer\">5\u20ac in Online Casinos<\/a> einzahlen und sofort das Gl\u00fcck auf die Probe stellen. Zudem gibt es immer wieder Anbieter, die mit entsprechenden Boni arbeiten, sodass neue Kunden oft einen Einzahlungsbonus gew\u00e4hrt bekommen, der als Willkommensbonus beworben wird.<\/p>\n<p>Auch der Bereich der Raumfahrt hat sich \u00fcber die Jahre ver\u00e4ndert und wird sich weiterhin ver\u00e4ndern &#8211; vor allem auch dank Bayreuth. Aber was hat man hier entdeckt, das f\u00fcr nachhaltige Ver\u00e4nderungen sorgen kann?<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Naehrstoffproduktion_in_der_Schwerelosigkeit\"><\/span><b>N\u00e4hrstoffproduktion in der Schwerelosigkeit<\/b><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Bei Zooplankton handelt es sich um kleine Organismen, die sich in den Nahrungsnetzen von Meeren und Seen befinden und ein sehr wichtiges Bindeglied darstellen. Denn einerseits ern\u00e4hren sie sich von den Mikroalgen, andererseits sind sie selbst das Futter f\u00fcr Fische oder sonstige Tiere, die im Wasser leben. Dabei bilden winzige Krebstiere den gr\u00f6\u00dften Anteil an Zooplankton, die aufgrund ihrer erzeugten Biomasse von gro\u00dfer \u00f6kologischer Wichtigkeit sind. Dazu geh\u00f6ren etwa Daphnien &#8211; das sind Wasserfl\u00f6he. \u201eLangj\u00e4hrige Forschungen mit diesen Organismen brachten uns auf die Idee, ob sie im Weltraum Biomasse erzeugen k\u00f6nnen, die dann einen lebenswichtigen Bestandteil der Astronautennahrung bilden\u201c, so Professor Dr. Christian Laforsch, der an der Universit\u00e4t Bayreuth besch\u00e4ftigt ist.<\/p>\n<p>Man hat \u00dcberlegungen angestellt, die hier im Kontext mit den bioregenerativen Lebenserhaltungssystemen stehen, an denen weltweit gearbeitet wird. Hier handelt es sich um \u201e<em>bioregenerative life support systems<\/em>\u201c &#8211; kurz: BLSS. Das sind k\u00fcnstlich geschaffene \u00d6kosysteme, die in der Lage sein sollen, dass der Mensch auf lange Sicht zuverl\u00e4ssig mit N\u00e4hrstoffen versorgt werden kann. Unter anderem in Gebieten, in denen es einen akuten Nahrungsmangel gibt, aber auch im Weltraum.<\/p>\n<p>Daf\u00fcr sollen auch die j\u00fcngsten Forschungsarbeiten der Bayreuther Forscher wegweisend sein. Denn Jessica Fischer hat in der Zeitschrift npj Microgravity belegt, dass es einige weitere vielversprechende Zooplankton-Organismen gibt, unter anderem Muschelkrebse, die sehr gute Voraussetzungen mit sich bringen, wenn es darum geht, die N\u00e4hrstoffproduktion eines BLSS in der Schwerelosigkeit voranzutreiben.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Erster_umbenannter_Flug_ist_wieder_sicher_gelandet\"><\/span><b>Erster umbenannter Flug ist wieder sicher gelandet<\/b><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Im Zuge eines <a href=\"https:\/\/www.golem.de\/sonstiges\/zustimmung\/auswahl.html?from=https%3A%2F%2Fwww.golem.de%2Fnews%2Ferfolgreicher-start-mehrere-missionen-fliegen-zum-mond-2501-192438.html&amp;referer=https%3A%2F%2Fwww.google.com%2F\" target=\"_blank\" rel=\"noopener noreferrer\">umbenannten Flugs des US Unternehmens<\/a> Blue Origin wurde zum ersten Mal getestet, welche Auswirkungen die Schwerelosigkeit auf molekulare Prozesse in Wasserfl\u00f6he haben kann. \u201eDiese Folgen m\u00fcssen bekannt sein, bevor man die Organismen in Lebenserhaltungssystemen im Weltraum verwenden kann. Wir freuen uns deshalb sehr dar\u00fcber, dass wir unsere Forschungsarbeiten mit Unterst\u00fctzung von Blue Origin entscheidend voranbringen konnten\u201c, so Dr. Miriam Knie, die Bayreuther Biologin. Das Flugger\u00e4t von Blue Origin mit dem Namen New Shepard, benannt also nach dem ersten Astronauten der USA Al Shepard, soll in weiterer Folge wissenschaftliche Experimente unterst\u00fctzen, vor allem, wenn es darum geht, die bemannte Raumfahrt weiterzubringen.<\/p>\n<p>Nach rund zehn Minuten ist New Shepard wieder gelandet. \u201eIn den n\u00e4chsten Wochen werden wir die in der Schwerelosigkeit gewonnenen Daten sorgf\u00e4ltig auswerten und mit unseren bisherigen Bayreuther Forschungsergebnissen abgleichen. Dann werden wir mehr dar\u00fcber wissen, wie gut sich Daphnien tats\u00e4chlich f\u00fcr den Einsatz in Raumstationen oder auf Langzeitfl\u00fcgen im Weltall eignen. Die Ergebnisse werden wir so bald wie m\u00f6glich der \u00d6ffentlichkeit vorstellen\u201c, so Dr. Knie.<\/p>\n<p>Von Seiten der Bayreuther Biologen ist man \u00fcberzeugt, dass die neuen Messdaten aufschlussreich sind, wenn es um weitere Forschungsfragen geht. Bislang ist nur wenig \u00fcber biologische Systeme bekannt, wenn es darum geht, wie sie auf Schwerkraft reagieren.<\/p>\n<blockquote><p>\u201eVor allem aber sollen die Experimente im Weltraum Erkenntnisse dar\u00fcber liefern, inwiefern Planktonorganismen auch auf der Erde f\u00fcr eine nachhaltige Nahrungsversorgung genutzt werden k\u00f6nnen\u201c, so Dr. Laforsch.<\/p><\/blockquote>","protected":false},"excerpt":{"rendered":"<p>Neue Technologien sorgen f\u00fcr nachhaltige Ver\u00e4nderungen. Wer jetzt an die USA oder China denkt, irrt. Auch Bayreuth ist in der<\/p>\n","protected":false},"author":2,"featured_media":4900,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[10],"tags":[],"class_list":["post-6762","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/posts\/6762","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/comments?post=6762"}],"version-history":[{"count":0,"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/posts\/6762\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/media\/4900"}],"wp:attachment":[{"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/media?parent=6762"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/categories?post=6762"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/tags?post=6762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}