{"id":700,"date":"2020-02-10T15:37:20","date_gmt":"2020-02-10T14:37:20","guid":{"rendered":"https:\/\/ekiwi.de\/?p=700"},"modified":"2020-02-10T15:37:20","modified_gmt":"2020-02-10T14:37:20","slug":"famisafe-jugend-und-kinderschutz-fuer-android-und-ios","status":"publish","type":"post","link":"https:\/\/ekiwi.de\/index.php\/700\/famisafe-jugend-und-kinderschutz-fuer-android-und-ios\/","title":{"rendered":"FamiSafe &#8211; Jugend- und Kinderschutz f\u00fcr Android und IOS"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_82_2 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Inhalt<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/ekiwi.de\/index.php\/700\/famisafe-jugend-und-kinderschutz-fuer-android-und-ios\/#Hauptfunktionen_von_Famisafe\" >Hauptfunktionen von Famisafe<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/ekiwi.de\/index.php\/700\/famisafe-jugend-und-kinderschutz-fuer-android-und-ios\/#Browserverlauf_und_Blockieren_von_Webseiten\" >Browserverlauf und Blockieren von Webseiten<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/ekiwi.de\/index.php\/700\/famisafe-jugend-und-kinderschutz-fuer-android-und-ios\/#Location-Tracking_und_Standortverlauf\" >Location-Tracking und Standortverlauf<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/ekiwi.de\/index.php\/700\/famisafe-jugend-und-kinderschutz-fuer-android-und-ios\/#Zeitbegrenzungen_fuer_Apps\" >Zeitbegrenzungen f\u00fcr Apps<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/ekiwi.de\/index.php\/700\/famisafe-jugend-und-kinderschutz-fuer-android-und-ios\/#Verdaechtige_Inhalte_und_Fotos\" >Verd\u00e4chtige Inhalte und Fotos<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/ekiwi.de\/index.php\/700\/famisafe-jugend-und-kinderschutz-fuer-android-und-ios\/#Bericht_von_Taetigkeiten\" >Bericht von T\u00e4tigkeiten<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/ekiwi.de\/index.php\/700\/famisafe-jugend-und-kinderschutz-fuer-android-und-ios\/#Installation_und_Konfiguration\" >Installation und Konfiguration<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/ekiwi.de\/index.php\/700\/famisafe-jugend-und-kinderschutz-fuer-android-und-ios\/#Fazit_%E2%80%93_Kinderschutz_mit_Famisafe\" >Fazit &#8211; Kinderschutz mit Famisafe<\/a><\/li><\/ul><\/nav><\/div>\n<p>Wird das erste Smartphone vom Nachwuchs gew\u00fcnscht, stehen Eltern oft vor einem Dilemma. Einerseits sind Smartphones eine praktische Sache, auf der anderen Seite er\u00f6ffnen diese auch viele unerw\u00fcnschte M\u00f6glichkeiten. Doch wie kann man f\u00fcr Sicherheit im Umgang mit dem Ger\u00e4t sorgen?<\/p>\n<p><!--more--><\/p>\n<p>Ein Smartphone ist praktisch, erlaubt es doch die schnelle Kommunikation zwischen Eltern und Kindern. Allerdings gibt es auch jede Menge negative Aspekte. Dies f\u00e4ngt bereits beim Konsum von YouTube-Videos an, geht \u00fcber s\u00fcchtig machende Apps und endet bei Gewaltbildern, welche \u00fcber WhatsApp getauscht werden.<\/p>\n<p>Kurzum ein komplett freies Telefon ist f\u00fcr Kinder und Jugendliche nicht geeignet. <\/p>\n<h2><span class=\"ez-toc-section\" id=\"Hauptfunktionen_von_Famisafe\"><\/span>Hauptfunktionen von Famisafe<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Alle Funktionen der <a href=\"https:\/\/famisafe.wondershare.com\/de\/?utm_source=webseite&#038;utm_medium=ewiki&#038;utm_campaign=dewsfm\" target=\"_blank\" rel=\"noopener noreferrer\">FamiSafe &#8211; Kindersicherungs App<\/a> lassen sich \u00fcber die Online-Oberfl\u00e4che im Internet konfigurieren. Genererell bieten Android-Telefone mehr M\u00f6glichkeiten als die Pendants der Firma Apple. Neben der Weboberfl\u00e4che steht auch eine Smartphone-App f\u00fcr das Eltern-Telefon zur Verf\u00fcgung. Damit kann auch von unterwegs Einfluss auf das Telefon des Kindes genommen werden und alle Funktionen konfiguriert und auch eingesehen werden.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"\/wp-content\/uploads\/2020\/02\/famisafe_0.jpg\" alt=\"\" width=\"653\" height=\"476\" class=\"aligncenter size-full wp-image-702\" srcset=\"\/wp-content\/uploads\/2020\/02\/famisafe_0.jpg 653w, \/wp-content\/uploads\/2020\/02\/famisafe_0-300x219.jpg 300w, \/wp-content\/uploads\/2020\/02\/famisafe_0-90x65.jpg 90w\" sizes=\"auto, (max-width: 653px) 100vw, 653px\" \/><\/p>\n<h3><span class=\"ez-toc-section\" id=\"Browserverlauf_und_Blockieren_von_Webseiten\"><\/span>Browserverlauf und Blockieren von Webseiten<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Webseiten lassen sich blockieren, dazu wird aufgezeichnet, welche Webseiten besucht werden. Die Auswahl erfolgt \u00fcber Kategorien, welche einzeln angew\u00e4hlt werden k\u00f6nnen. Ausnahmen lassen sich ebenfalls festlegen um einzelne Seiten freizuschalten.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"\/wp-content\/uploads\/2020\/02\/famisafe_3.jpg\" alt=\"\" width=\"750\" height=\"545\" class=\"aligncenter size-full wp-image-703\" srcset=\"\/wp-content\/uploads\/2020\/02\/famisafe_3.jpg 750w, \/wp-content\/uploads\/2020\/02\/famisafe_3-300x218.jpg 300w, \/wp-content\/uploads\/2020\/02\/famisafe_3-90x65.jpg 90w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<h3><span class=\"ez-toc-section\" id=\"Location-Tracking_und_Standortverlauf\"><\/span>Location-Tracking und Standortverlauf<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Mittels Tracking des Ortes, wissen Eltern, wo sich das Kind gerade befindet. Der Standort l\u00e4sst sich, in Echtzeit, verfolgen. Geofences lassen sich erstellen, sodass man sich benachrichtigen lassen kann, sofern das Kind eine Zone verl\u00e4sst. <\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"\/wp-content\/uploads\/2020\/02\/famisafe_1.jpg\" alt=\"\" width=\"750\" height=\"543\" class=\"aligncenter size-full wp-image-704\" srcset=\"\/wp-content\/uploads\/2020\/02\/famisafe_1.jpg 750w, \/wp-content\/uploads\/2020\/02\/famisafe_1-300x217.jpg 300w, \/wp-content\/uploads\/2020\/02\/famisafe_1-90x65.jpg 90w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<h3><span class=\"ez-toc-section\" id=\"Zeitbegrenzungen_fuer_Apps\"><\/span>Zeitbegrenzungen f\u00fcr Apps<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Spiele machen Spa\u00df, aber wenn die Hausaufgaben vernachl\u00e4ssigt werden, dann h\u00f6rt der Spa\u00df auch schnell wieder auf. Daher lassen sich Apps zeitlich begrenzen. Jede App l\u00e4sst sich konfigurieren. So kann WhatsApp generell und dauerhaft zugelassen werden, das Online-Spiel kann aber nur eine bestimmte Zeit am Tag gespielt werden.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"\/wp-content\/uploads\/2020\/02\/famisafe_4.jpg\" alt=\"\" width=\"600\" height=\"315\" class=\"aligncenter size-full wp-image-705\" srcset=\"\/wp-content\/uploads\/2020\/02\/famisafe_4.jpg 600w, \/wp-content\/uploads\/2020\/02\/famisafe_4-300x158.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>Auch eine Form des digitalen Hausarrests ist m\u00f6glich, indem das Telefon f\u00fcr eine bestimmte Zeit komplett gesperrt wird. <\/p>\n<p>Eine Nutzungsstatistik gibt Auskunft, welche Apps am meisten genutzt werden. Somit k\u00f6nnen Eltern auch schnell reagieren, wenn eine Nutzung aus dem Ruder l\u00e4uft.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Verdaechtige_Inhalte_und_Fotos\"><\/span>Verd\u00e4chtige Inhalte und Fotos<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Das Telefon l\u00e4sst sich auf verd\u00e4chtige Inhalte scannen. Hierbei werden verd\u00e4chtige Bilder erkannt und ggf. an die Eltern gemeldet. Gleiches gilt auch f\u00fcr explizite Inhalte, z.B. in Nachrichten. Dies erlaubt zu erkennen, ob das Kind Opfer von Mobbing ist.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"\/wp-content\/uploads\/2020\/02\/famisafe_5.png\" alt=\"\" width=\"641\" height=\"298\" class=\"aligncenter size-full wp-image-706\" srcset=\"\/wp-content\/uploads\/2020\/02\/famisafe_5.png 641w, \/wp-content\/uploads\/2020\/02\/famisafe_5-300x139.png 300w\" sizes=\"auto, (max-width: 641px) 100vw, 641px\" \/><\/p>\n<h3><span class=\"ez-toc-section\" id=\"Bericht_von_Taetigkeiten\"><\/span>Bericht von T\u00e4tigkeiten<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Famisafe loggt mit, was f\u00fcr Aktionen auf dem Telefon ausgef\u00fchrt worden sind. Welche Apps wurden verwendet, welche Apps wurden installiert und so weiter.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Installation_und_Konfiguration\"><\/span>Installation und Konfiguration<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Die Einrichtung ist einfach, zuerst meldet man sich beim Anbieter selbst an und loggt sich ein. Anschlie\u00dfend wird die App aus dem Telefon des Kindes installiert und eingerichtet. Eine Schritt-f\u00fcr-Schritt-Anleitung macht dies auch f\u00fcr nicht so technikaffine Leute m\u00f6glich.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"\/wp-content\/uploads\/2020\/02\/famisafe_einrichtung.jpg\" alt=\"\" width=\"439\" height=\"410\" class=\"aligncenter size-full wp-image-707\" srcset=\"\/wp-content\/uploads\/2020\/02\/famisafe_einrichtung.jpg 439w, \/wp-content\/uploads\/2020\/02\/famisafe_einrichtung-300x280.jpg 300w\" sizes=\"auto, (max-width: 439px) 100vw, 439px\" \/><\/p>\n<p>Anschlie\u00dfend kann das Ger\u00e4t \u00fcber die Webseite von Famisafe verwaltet werden. \u00dcber das Konfigurationsmen\u00fc lassen sich <a href=\"https:\/\/famisafe.wondershare.com\/de\/features\/?utm_source=webseite&#038;utm_medium=ewiki&#038;utm_campaign=dewsfm\" target=\"_blank\" rel=\"noopener noreferrer\">alle Funktionen von Famisafe<\/a> einstellen, aktivieren, deaktivieren und konfigurieren.<\/p>\n<p>Neben der Verwaltung \u00fcber die Webseite, steht auch eine Smartphone-App zur Verf\u00fcgung, welche die Konfiguration und Dateneinsicht \u00fcber das Smartphone erm\u00f6glicht. Hierzu installiert man einfach die gleiche App wie auf dem Kindertelefon, loggt sich aber als Eltern ein.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"\/wp-content\/uploads\/2020\/02\/famisafe_konfiguration.jpg\" alt=\"\" width=\"700\" height=\"512\" class=\"aligncenter size-full wp-image-708\" srcset=\"\/wp-content\/uploads\/2020\/02\/famisafe_konfiguration.jpg 700w, \/wp-content\/uploads\/2020\/02\/famisafe_konfiguration-300x219.jpg 300w, \/wp-content\/uploads\/2020\/02\/famisafe_konfiguration-90x65.jpg 90w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/p>\n<h2><span class=\"ez-toc-section\" id=\"Fazit_%E2%80%93_Kinderschutz_mit_Famisafe\"><\/span>Fazit &#8211; Kinderschutz mit Famisafe<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Viele Funktionen, welche die Sicherheit um Umgang des Smartphones f\u00fcr das Kind erleichtern. Nat\u00fcrlich ersetzt so eine App keine Erziehung und der Umgang mit dem Medium Internet, Apps und dem Smartphone sollte mit dem Kind diskutiert werden.<\/p>\n<p>Die Software erlaubt jedoch sehr genau einstellen zu k\u00f6nnen, was am Smartphone m\u00f6glich ist und vor allem wie lange. Dank Standort\u00fcbermittlung wissen Eltern immer wo sich die Kinder befinden und die automatische \u00dcberpr\u00fcfung auf unangemessene Inhalte erlaubt zu erkennen, ob der Nachwuchs eventuellem Mobbing ausgesetzt wird.<\/p>\n<p>Alle Funktionen k\u00f6nnen \u00fcber das eigene Smartphone oder der Webseite verwaltet werden.<\/p>","protected":false},"excerpt":{"rendered":"<p>Wird das erste Smartphone vom Nachwuchs gew\u00fcnscht, stehen Eltern oft vor einem Dilemma. Einerseits sind Smartphones eine praktische Sache, auf<\/p>\n","protected":false},"author":1,"featured_media":701,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[10],"tags":[132,83],"class_list":["post-700","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-sicherheit","tag-smartphone"],"_links":{"self":[{"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/posts\/700","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/comments?post=700"}],"version-history":[{"count":0,"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/posts\/700\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/media\/701"}],"wp:attachment":[{"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/media?parent=700"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/categories?post=700"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ekiwi.de\/index.php\/wp-json\/wp\/v2\/tags?post=700"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}